{"id":55468,"date":"2025-06-13T19:12:03","date_gmt":"2025-06-13T12:12:03","guid":{"rendered":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/"},"modified":"2025-06-13T19:12:03","modified_gmt":"2025-06-13T12:12:03","slug":"fete-de-la-musique-2025","status":"publish","type":"post","link":"https:\/\/www.ifi-id.com\/fr\/fete-de-la-musique-2025\/","title":{"rendered":"F\u00eate de la Musique 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"55468\" class=\"elementor elementor-55468 elementor-55456\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01decdd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01decdd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d282dc2\" data-id=\"d282dc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9fcd9a elementor-widget elementor-widget-text-editor\" data-id=\"d9fcd9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00c0 l\u2019approche des vacances scolaires de fin d\u2019ann\u00e9e, la F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays. Ce festival annuel, n\u00e9 en France en 1982 \u00e0 l\u2019initiative du Minist\u00e8re de la Culture, est c\u00e9l\u00e9br\u00e9 chaque 21 juin, jour symbolique du solstice d\u2019\u00e9t\u00e9 dans l\u2019h\u00e9misph\u00e8re nord.<\/p>\n<p>Bien que l\u2019Indon\u00e9sie ne connaisse pas de saisons marqu\u00e9es comme en Europe, l\u2019Institut Fran\u00e7ais d\u2019Indon\u00e9sie (IFI) souhaite transmettre l\u2019esprit joyeux et ensoleill\u00e9 de cette f\u00eate, qui c\u00e9l\u00e8bre la musique dans toute sa diversit\u00e9, accessible \u00e0 tous et dans l\u2019espace public.<\/p>\n<h3>Jakarta : Deux lieux embl\u00e9matiques pour une journ\u00e9e musicale<\/h3>\n<p>Le 21 juin 2025, Jakarta vibrera au rythme de la musique dans deux lieux en plein c\u0153ur de la ville :<\/p>\n<p>\u00c0 la station MRT Bundaran HI, le public pourra profiter d\u2019un concert exceptionnel de Adhitia Sofyan, artiste indon\u00e9sien reconnu pour son univers acoustique intime.<\/p>\n<p>\u00c0 Jalan Lada, Kota Tua (en face de la gare Beos), le duo fran\u00e7ais Ko Shin Moon se produira en live \u00e0 18h30. Ce duo fusionne musique folk, space disco et pop orientale, utilisant des instruments traditionnels comme le saz, l\u2019oud ou encore le sitar. Laur\u00e9ats du Prix Soci\u00e9t\u00e9 Ricard Live Music 2020, ils cr\u00e9ent une passerelle musicale entre les sonorit\u00e9s orientales et les textures \u00e9lectroniques analogiques.<\/p>\n<h3>Tourn\u00e9e de Ko Shin Moon en Indon\u00e9sie<\/h3>\n<p>Apr\u00e8s un passage en Cor\u00e9e du Sud, Ko Shin Moon entamera une tourn\u00e9e dans quatre grandes villes indon\u00e9siennes :<\/p>\n<ul>\n<li>Jakarta \u2013 21 juin (Kota Tua)<\/li>\n<li>Bandung \u2013 22 juin (NuArt Sculpture Park), avec Banda Neira et Rangkai, dans un \u00e9v\u00e9nement familial intitul\u00e9 Family Days Out<\/li>\n<li>Yogyakarta \u2013 24 juin (JNM Bloc, en collaboration avec ArtJog)<\/li>\n<li>Surabaya \u2013 26 juin (Soir\u00e9e, rooftop bar \u00e0 Four Points Pakuwon)<\/li>\n<\/ul>\n<h3>Autres villes participantes<\/h3>\n<ul>\n<li>\u00c0 Yogyakarta, deux dates sont pr\u00e9vues : le 21 juin \u00e0 l\u2019Auditorium de l\u2019IFI, et le 24 juin \u00e0 JNM Bloc.<\/li>\n<li>\u00c0 Surabaya, les festivit\u00e9s se d\u00e9rouleront les 21 et 26 juin, respectivement \u00e0 l\u2019IFI Surabaya (AJBS) et au rooftop Soir\u00e9e.<\/li>\n<li>D\u2019autres \u00e9v\u00e9nements se tiendront \u00e9galement \u00e0 Medan, Makassar et Denpasar, chacun avec sa propre programmation artistique.<\/li>\n<\/ul>\n<h3>\u00c9v\u00e9nement sp\u00e9cial \u00e0 Jakarta : Soir\u00e9e Karaok\u00e9<\/h3>\n<p>Pour les habitant\u00b7e\u00b7s de Jakarta et ses environs, un moment festif \u00e0 ne pas manquer : la Soir\u00e9e Karaok\u00e9 \u00e0 la M\u00e9diath\u00e8que de l\u2019IFI Thamrin le 24 juin 2025 \u00e0 18h30 \u2013 un rendez-vous convivial pour chanter ensemble dans une ambiance d\u00e9contract\u00e9e.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.<\/p>\n","protected":false},"author":8,"featured_media":55460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[145,151,387],"class_list":["post-55468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-culture","tag-musique","tag-national"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F\u00eate de la Musique 2025 - Institut fran\u00e7ais Indon\u00e9sie<\/title>\n<meta name=\"description\" content=\"La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00eate de la Musique 2025\" \/>\n<meta property=\"og:description\" content=\"La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Institut fran\u00e7ais Indon\u00e9sie\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-13T12:12:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ghaisani Azizi Nurul Rizki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ghaisani Azizi Nurul Rizki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\"},\"author\":{\"name\":\"Ghaisani Azizi Nurul Rizki\",\"@id\":\"https:\/\/www.ifi-id.com\/#\/schema\/person\/a4eae510c216615f5c0f4e02f4edff1b\"},\"headline\":\"F\u00eate de la Musique 2025\",\"datePublished\":\"2025-06-13T12:12:03+00:00\",\"dateModified\":\"2025-06-13T12:12:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\/\/www.ifi-id.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg\",\"keywords\":[\"Culture\",\"Musique\",\"National\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\",\"url\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\",\"name\":\"F\u00eate de la Musique 2025 - Institut fran\u00e7ais Indon\u00e9sie\",\"isPartOf\":{\"@id\":\"https:\/\/www.ifi-id.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg\",\"datePublished\":\"2025-06-13T12:12:03+00:00\",\"dateModified\":\"2025-06-13T12:12:03+00:00\",\"description\":\"La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage\",\"url\":\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg\",\"contentUrl\":\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ifi-id.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non classifi\u00e9(e)\",\"item\":\"https:\/\/www.ifi-id.com\/fr\/category\/non-classifiee\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00eate de la Musique 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ifi-id.com\/#website\",\"url\":\"https:\/\/www.ifi-id.com\/\",\"name\":\"Institut fran\u00e7ais Indon\u00e9sie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ifi-id.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ifi-id.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ifi-id.com\/#organization\",\"name\":\"Institut fran\u00e7ais Indon\u00e9sie\",\"url\":\"https:\/\/www.ifi-id.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ifi-id.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2022\/12\/IFI_New_Logo.jpg\",\"contentUrl\":\"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2022\/12\/IFI_New_Logo.jpg\",\"width\":666,\"height\":444,\"caption\":\"Institut fran\u00e7ais Indon\u00e9sie\"},\"image\":{\"@id\":\"https:\/\/www.ifi-id.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ifi-id.com\/#\/schema\/person\/a4eae510c216615f5c0f4e02f4edff1b\",\"name\":\"Ghaisani Azizi Nurul Rizki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ifi-id.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8ce4836ecc2a94798a84b768a7f20853?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8ce4836ecc2a94798a84b768a7f20853?s=96&d=mm&r=g\",\"caption\":\"Ghaisani Azizi Nurul Rizki\"},\"url\":\"https:\/\/www.ifi-id.com\/fr\/author\/azizi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00eate de la Musique 2025 - Institut fran\u00e7ais Indon\u00e9sie","description":"La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"F\u00eate de la Musique 2025","og_description":"La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.","og_url":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/","og_site_name":"Institut fran\u00e7ais Indon\u00e9sie","article_published_time":"2025-06-13T12:12:03+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg","type":"image\/jpeg"}],"author":"Ghaisani Azizi Nurul Rizki","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ghaisani Azizi Nurul Rizki","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#article","isPartOf":{"@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/"},"author":{"name":"Ghaisani Azizi Nurul Rizki","@id":"https:\/\/www.ifi-id.com\/#\/schema\/person\/a4eae510c216615f5c0f4e02f4edff1b"},"headline":"F\u00eate de la Musique 2025","datePublished":"2025-06-13T12:12:03+00:00","dateModified":"2025-06-13T12:12:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.ifi-id.com\/#organization"},"image":{"@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg","keywords":["Culture","Musique","National"],"articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/","url":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/","name":"F\u00eate de la Musique 2025 - Institut fran\u00e7ais Indon\u00e9sie","isPartOf":{"@id":"https:\/\/www.ifi-id.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg","datePublished":"2025-06-13T12:12:03+00:00","dateModified":"2025-06-13T12:12:03+00:00","description":"La F\u00eate de la Musique revient en Indon\u00e9sie avec une s\u00e9rie de concerts gratuits et ouverts au public dans plusieurs villes du pays.","breadcrumb":{"@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#primaryimage","url":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg","contentUrl":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2025\/06\/WB-FDLM-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.ifi-id.com\/fete-de-la-musique-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ifi-id.com\/"},{"@type":"ListItem","position":2,"name":"Non classifi\u00e9(e)","item":"https:\/\/www.ifi-id.com\/fr\/category\/non-classifiee\/"},{"@type":"ListItem","position":3,"name":"F\u00eate de la Musique 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.ifi-id.com\/#website","url":"https:\/\/www.ifi-id.com\/","name":"Institut fran\u00e7ais Indon\u00e9sie","description":"","publisher":{"@id":"https:\/\/www.ifi-id.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ifi-id.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ifi-id.com\/#organization","name":"Institut fran\u00e7ais Indon\u00e9sie","url":"https:\/\/www.ifi-id.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ifi-id.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2022\/12\/IFI_New_Logo.jpg","contentUrl":"https:\/\/www.ifi-id.com\/wp-content\/uploads\/2022\/12\/IFI_New_Logo.jpg","width":666,"height":444,"caption":"Institut fran\u00e7ais Indon\u00e9sie"},"image":{"@id":"https:\/\/www.ifi-id.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ifi-id.com\/#\/schema\/person\/a4eae510c216615f5c0f4e02f4edff1b","name":"Ghaisani Azizi Nurul Rizki","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ifi-id.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8ce4836ecc2a94798a84b768a7f20853?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ce4836ecc2a94798a84b768a7f20853?s=96&d=mm&r=g","caption":"Ghaisani Azizi Nurul Rizki"},"url":"https:\/\/www.ifi-id.com\/fr\/author\/azizi\/"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/posts\/55468"}],"collection":[{"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/comments?post=55468"}],"version-history":[{"count":1,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/posts\/55468\/revisions"}],"predecessor-version":[{"id":55469,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/posts\/55468\/revisions\/55469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/media\/55460"}],"wp:attachment":[{"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/media?parent=55468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/categories?post=55468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ifi-id.com\/fr\/wp-json\/wp\/v2\/tags?post=55468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}